{"id":13424,"date":"2024-03-15T13:02:21","date_gmt":"2024-03-15T20:02:21","guid":{"rendered":"http:\/\/www.ehsfalconnews.org\/?p=13424"},"modified":"2024-03-18T10:20:04","modified_gmt":"2024-03-18T17:20:04","slug":"photo-gallery-ehs-softball-team-takes-pies-to-the-face","status":"publish","type":"post","link":"http:\/\/www.ehsfalconnews.org\/index.php\/2024\/03\/15\/photo-gallery-ehs-softball-team-takes-pies-to-the-face\/","title":{"rendered":"Photo Gallery: EHS Softball Team Takes Pies to the Face"},"content":{"rendered":"\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"851\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-1024x851.jpg\" alt=\"\" class=\"wp-image-13414\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-1024x851.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-300x249.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-768x638.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-1536x1276.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-2048x1701.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-17-570x473.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Junior Layla Burgess gets pied by senior Austyn Woolcott. <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-gallery alignwide has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"709\" data-id=\"13435\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3-1024x709.jpg\" alt=\"\" class=\"wp-image-13435\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3-1024x709.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3-300x208.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3-768x532.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3-1536x1064.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3-570x395.jpg 570w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-3.jpg 1727w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">P.E. teacher Rob Lee and senior Quinton Buckland racing in a relay. <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" data-id=\"13432\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-1024x600.jpg\" alt=\"\" class=\"wp-image-13432\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-1024x600.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-300x176.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-768x450.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-1536x900.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-2048x1201.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-2-570x334.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">EHS track students racing in a relay.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"597\" data-id=\"13415\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666-1024x597.jpg\" alt=\"\" class=\"wp-image-13415\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666-1024x597.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666-300x175.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666-768x448.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666-1536x896.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666-570x332.jpg 570w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-7-e1710439044666.jpg 1614w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">EHS CTE teacher David Johnson leads in the relay against junior Kyler Colwell.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"722\" data-id=\"13411\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5-1024x722.jpg\" alt=\"\" class=\"wp-image-13411\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5-1024x722.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5-300x211.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5-768x541.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5-1536x1082.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5-570x402.jpg 570w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-5.jpg 1696w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">German teacher John Wagner and junior Kiara Tierce. <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" data-id=\"13408\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-1024x632.jpg\" alt=\"\" class=\"wp-image-13408\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-1024x632.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-300x185.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-768x474.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-1536x948.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-2048x1264.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-4-570x352.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Math teacher Ken Best and senior Austyn Woolcott racing in the relay.  <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"664\" data-id=\"13433\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-1024x664.jpg\" alt=\"\" class=\"wp-image-13433\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-1024x664.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-300x195.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-768x498.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-1536x996.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-2048x1329.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-13-570x370.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sophomore Taylor Bennett swinging a bat. <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"701\" data-id=\"13423\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-1024x701.jpg\" alt=\"\" class=\"wp-image-13423\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-1024x701.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-300x205.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-768x526.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-1536x1051.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-2048x1401.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-10-570x390.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Senior Brenden Davis up to bat.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"649\" data-id=\"13436\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-1024x649.jpg\" alt=\"\" class=\"wp-image-13436\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-1024x649.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-300x190.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-768x487.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-1536x973.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-2048x1298.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-14-scaled-e1710438856220-570x361.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Senior Ethan Bennett spinning around before hitting.  <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"624\" data-id=\"13409\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761-1024x624.jpg\" alt=\"\" class=\"wp-image-13409\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761-1024x624.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761-300x183.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761-768x468.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761-1536x937.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761-570x348.jpg 570w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-15-scaled-e1710438790761.jpg 2022w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sophomore Marvin Hambrick spinning around in a circle before up to bat.  <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"801\" data-id=\"13420\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-1024x801.jpg\" alt=\"\" class=\"wp-image-13420\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-1024x801.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-300x235.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-768x600.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-1536x1201.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-2048x1601.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-9-570x446.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Senior Johnny Rhodes gets pied by senior Austyn Woolcott.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" data-id=\"13417\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-1024x770.jpg\" alt=\"\" class=\"wp-image-13417\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-1024x770.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-300x226.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-768x578.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-1536x1155.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-2048x1541.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-8-570x429.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Senior Johnny Rhodes gets pied by senior Austyn Woolcott.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"801\" data-id=\"13416\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-1024x801.jpg\" alt=\"\" class=\"wp-image-13416\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-1024x801.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-300x235.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-768x601.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-1536x1202.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-2048x1603.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-18-570x446.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Senior Johnny Rhodes pieing Dayshah Conklin.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"878\" data-id=\"13428\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-1024x878.jpg\" alt=\"\" class=\"wp-image-13428\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-1024x878.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-300x257.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-768x659.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-1536x1318.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-2048x1757.jpg 2048w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-22-570x489.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sophomore Marvin Hambrick pieing Ashen Inmen.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"850\" data-id=\"13412\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16-1024x850.jpg\" alt=\"\" class=\"wp-image-13412\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16-1024x850.jpg 1024w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16-300x249.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16-768x637.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16-1536x1275.jpg 1536w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16-570x473.jpg 570w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-16.jpg 1971w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Senior Austyn Woolcott pieing junior Layla Burgess.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"963\" height=\"875\" data-id=\"13422\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-20.jpg\" alt=\"\" class=\"wp-image-13422\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-20.jpg 963w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-20-300x273.jpg 300w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-20-768x698.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-20-570x518.jpg 570w\" sizes=\"auto, (max-width: 963px) 100vw, 963px\" \/><figcaption class=\"wp-element-caption\">Sophomore Taylor Bennett after getting pied.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"1024\" data-id=\"13429\" src=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-1-744x1024.jpg\" alt=\"\" class=\"wp-image-13429\" srcset=\"http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-1-744x1024.jpg 744w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-1-218x300.jpg 218w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-1-768x1057.jpg 768w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-1-570x785.jpg 570w, http:\/\/www.ehsfalconnews.org\/wp-content\/uploads\/2024\/03\/Spirit-week-assembly-1.jpg 805w\" sizes=\"auto, (max-width: 744px) 100vw, 744px\" \/><figcaption class=\"wp-element-caption\">Sophomore Taylor Bennett is all smiles after &#8220;sharing&#8221; her pie with her grandmother and EHS teacher Teri Moen. (Photo by EHS staff member McKenzie Lyon)<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center\">Elmira High School students and staff enjoyed a spring sports assembly with fun games, cheering, school spirit and pie to the face. (Photos by Falcon News)   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>The assembly introduces spring sports and has some friendly competition<\/p>\n","protected":false},"author":10,"featured_media":13414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":{"0":"post-13424","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"czr-hentry"},"_links":{"self":[{"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/posts\/13424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/comments?post=13424"}],"version-history":[{"count":7,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/posts\/13424\/revisions"}],"predecessor-version":[{"id":13511,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/posts\/13424\/revisions\/13511"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/media\/13414"}],"wp:attachment":[{"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/media?parent=13424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/categories?post=13424"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.ehsfalconnews.org\/index.php\/wp-json\/wp\/v2\/tags?post=13424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}